{"id":5288,"date":"2026-03-30T10:48:30","date_gmt":"2026-03-30T02:48:30","guid":{"rendered":"https:\/\/en.kn-nanjing.com\/?p=5288"},"modified":"2026-05-13T16:34:48","modified_gmt":"2026-05-13T08:34:48","slug":"focusing-on-ai-frontiers-empowering-intelligent-manufacturing-kangni-holds-special-training-on-key-ai-technologies-enablement-and-innovative-applications","status":"publish","type":"post","link":"https:\/\/en.kn-nanjing.com\/de\/focusing-on-ai-frontiers-empowering-intelligent-manufacturing-kangni-holds-special-training-on-key-ai-technologies-enablement-and-innovative-applications\/","title":{"rendered":"Fokus auf KI-Frontier-Technologien, Bef\u00e4higung der intelligenten Fertigung \u2013 Kangni veranstaltet eine Sonderschulung zu \u201eSchl\u00fcsseltechnologien der KI: Bef\u00e4higung und innovative Anwendungen\u201c"},"content":{"rendered":"<p>10. M\u00e4rz 2026<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"840\" height=\"537\" src=\"https:\/\/en.kn-nanjing.com\/wp-content\/uploads\/2026\/03\/screenshot-2026-03-30-104655-681.jpg\" alt=\"screenshot 2026 03 30 104655 681\" class=\"wp-image-5289\" srcset=\"https:\/\/en.kn-nanjing.com\/wp-content\/uploads\/2026\/03\/screenshot-2026-03-30-104655-681.jpg 840w, https:\/\/en.kn-nanjing.com\/wp-content\/uploads\/2026\/03\/screenshot-2026-03-30-104655-681-300x192.jpg 300w, https:\/\/en.kn-nanjing.com\/wp-content\/uploads\/2026\/03\/screenshot-2026-03-30-104655-681-768x491.jpg 768w, https:\/\/en.kn-nanjing.com\/wp-content\/uploads\/2026\/03\/screenshot-2026-03-30-104655-681-18x12.jpg 18w, https:\/\/en.kn-nanjing.com\/wp-content\/uploads\/2026\/03\/screenshot-2026-03-30-104655-681-600x384.jpg 600w\" sizes=\"auto, (max-width: 840px) 100vw, 840px\" \/><figcaption class=\"wp-element-caption\">Du Wei, General Manager der Zhongzhi Manufacturing Company, hielt einen Fachvortrag zum Thema \u201eVerk\u00f6rperte KI und humanoide Roboter\u201c<\/figcaption><\/figure>\n\n\n\n<p>Zur Beschleunigung der Umsetzung der Strategie \u201eKangni-Fertigungsstrategie 2030\u201c und als Reaktion auf die Welle technologischer Ver\u00e4nderungen im Bereich der k\u00fcnstlichen Intelligenz veranstaltete die Abteilung f\u00fcr Informationsmanagement der Kangni-Gruppe am Vormittag des 6. M\u00e4rz eine Sonder-Schulung zum Thema \u201eSchl\u00fcsseltechnologien der KI: Bef\u00e4higung und innovative Anwendungen\u201c. Als Referenten wurden Du Wei, General Manager der Zhongzhi Manufacturing Company, sowie der stellvertretende General Manager Yu Zhimin eingeladen. Zu den Teilnehmenden z\u00e4hlten Zhang Hongbin, Assistent des Pr\u00e4sidenten von Kangni, s\u00e4mtliche Mitglieder des Projektteams \u201eKangni-Fertigungsstrategie 2030\u201c sowie einschl\u00e4gige Fachkr\u00e4fte aus den Gesch\u00e4ftsbereichen. Die Veranstaltung wurde von Wang Hongtao, Leiter der Abteilung f\u00fcr Informationsmanagement, moderiert.<\/p>\n\n\n\n<p>Diese Schulung konzentrierte sich auf zwei Kerndimensionen: \u201eVerk\u00f6rperte KI und humanoide Roboter\u201c und \u201eZentrale KI-Technologien und Kangnis Anwendungsstrategie\u201c. Durch systematische Wissensvermittlung und szenariobasierte Fallanalysen wurde eine unternehmensweite Grundlage f\u00fcr KI-Kompetenzen geschaffen, die Transformation von KI von einem \u201etechnologischen Konzept\u201c zu einer \u201egesch\u00e4ftlichen Triebkraft\u201c vorangetrieben und die Tiefe des Verst\u00e4ndnisses sowie die Anwendungskompetenz des Teams im Bereich der k\u00fcnstlichen Intelligenz umfassend verbessert.<\/p>\n\n\n\n<p>In dem Vortrag zum Thema \u201eVerk\u00f6rperte KI und humanoide Roboter\u201c stellte Du Wei systematisch das Konzept, die Entwicklungsgeschichte und den aktuellen Stand von verk\u00f6rperter KI vor. Er erl\u00e4uterte ausf\u00fchrlich die zentralen technologischen Entwicklungspfade, Trends und Anwendungsszenarien humanoider Roboter. Dar\u00fcber hinaus gab er auf Grundlage der industriellen Eigenschaften und der tats\u00e4chlichen Situation der Sparte Schienenverkehrstechnik von Kangni erste Bewertungen und Empfehlungen ab und bot damit eine vorausschauende Perspektive f\u00fcr die zuk\u00fcnftige Erkundung neuer Formen intelligenter Fertigung.<\/p>\n\n\n\n<p>In dem anschlie\u00dfenden Vortrag zum Thema \u201eZentrale KI-Technologien und Kangnis Anwendungsstrategie\u201c konzentrierte sich Yu Zhimin, stellvertretender General Manager der Zhongzhi Manufacturing Company, auf die Kerntechnologien der KI und analysierte die technologische Landschaft der k\u00fcnstlichen Intelligenz aus verschiedenen Dimensionen wie \u201eDaten, Algorithmen, Rechenleistung und Anwendungsszenarien\u201c. Unter Einbeziehung der gesamten Wertsch\u00f6pfungskette des Unternehmens \u2013 von Marketing, Forschung und Entwicklung, Prozessen und Produktion \u00fcber die Lieferkette bis hin zu Produktservices und intelligentem Management \u2013 entwickelte er anhand praxisnaher Fallbeispiele einen zuk\u00fcnftigen Entwicklungsplan sowie eine Umsetzungs-Roadmap f\u00fcr den KI-Einsatz im Unternehmen.<\/p>\n\n\n\n<p>W\u00e4hrend der Schulung f\u00fchrten die Teilnehmenden intensive Diskussionen \u00fcber die Integration von KI-Technologien in die Gesch\u00e4ftsprozesse. Zhang Hongbin, Assistent des Pr\u00e4sidenten, betonte in seiner Zusammenfassung, dass \u201edie Bew\u00e4ltigung von Schmerzpunkten und die Schaffung von Mehrwert durch die aktive Nutzung von KI\u201c als zentrale Leitlinie dienen m\u00fcsse, um die k\u00fcnstliche Intelligenz von einem technologischen Konzept in eine gesch\u00e4ftliche Triebkraft zu \u00fcberf\u00fchren. Er forderte alle Abteilungen auf, diese Schulung als Anlass zu nutzen, vertiefte KI-spezifische Fachdiskussionen durchzuf\u00fchren und die Umsetzung der Strategie \u201eKangni-Fertigungsstrategie 2030\u201c umfassend durch KI gezielt zu bef\u00e4higen und zu unterst\u00fctzen.<\/p>","protected":false},"excerpt":{"rendered":"<p>March 10, 2026 To accelerate the implementation of \u201cKangni Manufacturing 2030\u201d strategy and respond to the wave of artificial intelligence technological change, on the morning of March 6, Kangni\u00a0Group Information Management Department held a special training session on \u201cKey AI Technologies Enablement and Innovative Applications.\u201d The training invited Du Wei, General Manager of Zhongzhi Manufacturing &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/en.kn-nanjing.com\/de\/focusing-on-ai-frontiers-empowering-intelligent-manufacturing-kangni-holds-special-training-on-key-ai-technologies-enablement-and-innovative-applications\/\"> <span class=\"screen-reader-text\">Fokus auf KI-Frontier-Technologien, Bef\u00e4higung der intelligenten Fertigung \u2013 Kangni veranstaltet eine Sonderschulung zu \u201eSchl\u00fcsseltechnologien der KI: Bef\u00e4higung und innovative Anwendungen\u201c<\/span> Mehr lesen \"<\/a><\/p>","protected":false},"author":2,"featured_media":5289,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"yst_prominent_words":[],"class_list":["post-5288","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/en.kn-nanjing.com\/de\/wp-json\/wp\/v2\/posts\/5288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/en.kn-nanjing.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/en.kn-nanjing.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/en.kn-nanjing.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/en.kn-nanjing.com\/de\/wp-json\/wp\/v2\/comments?post=5288"}],"version-history":[{"count":1,"href":"https:\/\/en.kn-nanjing.com\/de\/wp-json\/wp\/v2\/posts\/5288\/revisions"}],"predecessor-version":[{"id":5290,"href":"https:\/\/en.kn-nanjing.com\/de\/wp-json\/wp\/v2\/posts\/5288\/revisions\/5290"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/en.kn-nanjing.com\/de\/wp-json\/wp\/v2\/media\/5289"}],"wp:attachment":[{"href":"https:\/\/en.kn-nanjing.com\/de\/wp-json\/wp\/v2\/media?parent=5288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/en.kn-nanjing.com\/de\/wp-json\/wp\/v2\/categories?post=5288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/en.kn-nanjing.com\/de\/wp-json\/wp\/v2\/tags?post=5288"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/en.kn-nanjing.com\/de\/wp-json\/wp\/v2\/yst_prominent_words?post=5288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}